{"id":7086,"date":"2023-08-13T15:53:41","date_gmt":"2023-08-13T13:53:41","guid":{"rendered":"https:\/\/www.elbenwald.de\/Festival\/?p=7086"},"modified":"2023-08-25T17:00:41","modified_gmt":"2023-08-25T15:00:41","slug":"charity-mit-herz","status":"publish","type":"post","link":"https:\/\/www.elbenwald.de\/Festival\/2023\/08\/13\/charity-mit-herz\/","title":{"rendered":"Charity mit Herz"},"content":{"rendered":"<p>Heute um 18:45 Uhr wird es auf der Seeb\u00fchne emotional und gro\u00dfz\u00fcgig zugleich! Wir pr\u00e4sentieren eine spezielle Charity-Auktion zugunsten des <strong>Johanniter-Kinderhaus Pusteblume<\/strong> in Burg (Spreewald). Hier hast Du die Chance, nicht nur etwas Gutes zu tun, sondern auch einzigartige Sch\u00e4tze zu ergattern.<\/p>\n<p>Mit dabei sind die grandiosen Forzarello und Harpo Speaks, die diesen Programmpunkt mit ihrem Charme und Talent bereichern werden.<\/p>\n<p>Was erwartet Dich auf der Auktion?<\/p>\n<ol>\n<li>Ein handbemalter Sch\u00e4del, gro\u00dfz\u00fcgig gestiftet von Dinoshop-Nerdstuff \u2013 ein echter Blickfang f\u00fcr jeden Raum!<\/li>\n<li>Eine Gitarre, signiert vom talentierten Tommy Krappweis pers\u00f6nlich. Und das Beste? Ein Verst\u00e4rker, St\u00e4nder und Tasche sind auch im Paket inbegriffen.<\/li>\n<li>Ein absolutes Einzelst\u00fcck f\u00fcr Star Wars-Fans: Droide Lola, handgefertigt und handbemalt, gestiftet von der legend\u00e4ren 501st Legion.<\/li>\n<li>Und f\u00fcr alle Action-Fans? Nerf-Waffen, um mit Freunden den ultimativen Spa\u00df zu haben.<\/li>\n<\/ol>\n<p>Jeder Cent der Auktion flie\u00dft in den guten Zweck, also \u00f6ffne Dein Herz (und vielleicht auch Dein Portemonnaie) und unterst\u00fctze das Kinderhaus Pusteblume. Wir sehen uns auf der Seeb\u00fchne! \ud83c\udfb6\u2764\ufe0f\ud83c\udfb8\ud83c\udfa8\ud83e\udd16<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7087\" src=\"https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-1024x1024.jpg\" alt=\"\" width=\"760\" height=\"760\" srcset=\"https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-1024x1024.jpg 1024w, https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-300x300.jpg 300w, https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-150x150.jpg 150w, https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-768x768.jpg 768w, https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-1536x1536.jpg 1536w, https:\/\/www.elbenwald.de\/Festival\/wp-content\/uploads\/EWF2023_Johanna_Lenth-2-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute um 18:45 Uhr wird es auf der Seeb\u00fchne emotional und gro\u00dfz\u00fcgig zugleich! Wir pr\u00e4sentieren eine spezielle Charity-Auktion zugunsten des Johanniter-Kinderhaus Pusteblume in Burg (Spreewald).&hellip;<\/p>\n<p><a class=\"moretag\" href=\"https:\/\/www.elbenwald.de\/Festival\/2023\/08\/13\/charity-mit-herz\/\">Mehr lesen &rarr;<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7086","post","type-post","status-publish","format-standard","hentry","category-news"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/posts\/7086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/comments?post=7086"}],"version-history":[{"count":3,"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/posts\/7086\/revisions"}],"predecessor-version":[{"id":7226,"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/posts\/7086\/revisions\/7226"}],"wp:attachment":[{"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/media?parent=7086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/categories?post=7086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elbenwald.de\/Festival\/wp-json\/wp\/v2\/tags?post=7086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}